{"id":79,"date":"2025-01-09T12:55:35","date_gmt":"2025-01-09T12:55:35","guid":{"rendered":"https:\/\/dover-dunkirk.com\/de\/duinkerken-naar-dover\/"},"modified":"2025-01-09T15:44:10","modified_gmt":"2025-01-09T15:44:10","slug":"von-duenkirchen-nach-dover","status":"publish","type":"page","link":"https:\/\/dover-dunkirk.com\/de\/","title":{"rendered":"Von D\u00fcnkirchen nach Dover"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"79\" class=\"elementor elementor-79\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68ec92c8 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68ec92c8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c69e5c1\" data-id=\"3c69e5c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10c5b987 elementor-widget elementor-widget-heading\" data-id=\"10c5b987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Von D\u00fcnkirchen nach Dover<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12549432 elementor-widget elementor-widget-heading\" data-id=\"12549432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">In nur 2 Stunden mit der F\u00e4hre bist du in England: Dunkerque-Dover<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12a84285 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12a84285\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-13da3653\" data-id=\"13da3653\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12ab9410 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"12ab9410\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff;\">\u21d2 Die beste Alternative f\u00fcr die \u00dcberfahrt von Calais nach Dover <br>\u21d2 Dunkerque ist ein leicht erreichbarer Hafen aus Deutschland. <\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d11b26e\" data-id=\"6d11b26e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5abb71de elementor-align-right elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"5abb71de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:10,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl elementor-animation-shrink\" href=\"https:\/\/dover-dunkirk.com\/de\/go\/dunkirk-dover\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tickets und Preise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37701a8a elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37701a8a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66cda3c2\" data-id=\"66cda3c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10232261 elementor-widget elementor-widget-heading\" data-id=\"10232261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-small\">D\u00fcnkirchen nach Dover<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b78b8 elementor-widget elementor-widget-breadcrumbs\" data-id=\"d4b78b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/dover-dunkirk.com\/de\/\">D\u00fcnkirchen nach Dover<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b2145c2 elementor-align-right elementor-mobile-align-right elementor-widget elementor-widget-button\" data-id=\"3b2145c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;mobile&quot;],&quot;sticky_offset&quot;:8,&quot;sticky_effects_offset_mobile&quot;:0,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-shrink\" href=\"https:\/\/dover-dunkirk.com\/de\/go\/dunkirk-dover\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tickets und Preise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ac41524 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ac41524\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-110beeae\" data-id=\"110beeae\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-321d0f61 elementor-view-framed elementor-widget__width-auto elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"321d0f61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-498df0c2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"498df0c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Verglichen mit Calais: etwas k\u00fcrzere Anfahrt, etwas l\u00e4ngere \u00dcberfahrt.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4a4d77d\" data-id=\"4a4d77d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ef6cf27 elementor-view-framed elementor-widget__width-auto elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"2ef6cf27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ticket-alt\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M128 160h320v192H128V160zm400 96c0 26.51 21.49 48 48 48v96c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48v-96c26.51 0 48-21.49 48-48s-21.49-48-48-48v-96c0-26.51 21.49-48 48-48h480c26.51 0 48 21.49 48 48v96c-26.51 0-48 21.49-48 48zm-48-104c0-13.255-10.745-24-24-24H120c-13.255 0-24 10.745-24 24v208c0 13.255 10.745 24 24 24h336c13.255 0 24-10.745 24-24V152z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35625c8c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"35625c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Buche deine Tickets online, um \u00dcberraschungen zu vermeiden.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7cd4584a\" data-id=\"7cd4584a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be0e5 elementor-view-framed elementor-widget__width-auto elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5be0e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ship\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496.616 372.639l70.012-70.012c16.899-16.9 9.942-45.771-12.836-53.092L512 236.102V96c0-17.673-14.327-32-32-32h-64V24c0-13.255-10.745-24-24-24H248c-13.255 0-24 10.745-24 24v40h-64c-17.673 0-32 14.327-32 32v140.102l-41.792 13.433c-22.753 7.313-29.754 36.173-12.836 53.092l70.012 70.012C125.828 416.287 85.587 448 24 448c-13.255 0-24 10.745-24 24v16c0 13.255 10.745 24 24 24 61.023 0 107.499-20.61 143.258-59.396C181.677 487.432 216.021 512 256 512h128c39.979 0 74.323-24.568 88.742-59.396C508.495 491.384 554.968 512 616 512c13.255 0 24-10.745 24-24v-16c0-13.255-10.745-24-24-24-60.817 0-101.542-31.001-119.384-75.361zM192 128h256v87.531l-118.208-37.995a31.995 31.995 0 0 0-19.584 0L192 215.531V128z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28a1a5f0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"28a1a5f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Ab 92\u202f\u20ac f\u00fcr ein Auto mit 4 Personen.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2acf9e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2acf9e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-654bfba\" data-id=\"654bfba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2900cf52 elementor-widget elementor-widget-heading\" data-id=\"2900cf52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kurze \u00dcberfahrt von England nach Frankreich. Die Alternative zu (\u00fcberf\u00fclltem) Calais!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f6521b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f6521b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bacaf09\" data-id=\"6bacaf09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b591459 elementor-widget elementor-widget-heading\" data-id=\"3b591459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diese \u00dcberfahrt in K\u00fcrze.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39bbf440 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39bbf440\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39e4baf8\" data-id=\"39e4baf8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bda08b5 elementor-widget elementor-widget-text-editor\" data-id=\"1bda08b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die \u00dcberfahrt von D\u00fcnkirchen nach Dover hat viele Vorteile. Es dauert nur eine halbe Stunde l\u00e4nger als \u00fcber Calais und die Fahrt aus Deutschland ist 20 Minuten k\u00fcrzer. So verlierst du nur etwa 10 Minuten. A<strong>u\u00dferdem ist die \u00dcberfahrt ruhiger und du kannst vor allem l\u00e4nger auf der F\u00e4hre entspannen<\/strong>!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-493adf80\" data-id=\"493adf80\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6634439b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6634439b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">9 \u00dcberfahrten pro Tag (hin) und 9 zur\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alle 2 Stunden eine Abfahrt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Die \u00dcberfahrt dauert 2 Stunden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tickets ab 92\u202f\u20ac pro Auto (bis zu 4 Personen)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ungef\u00e4hr 64 km \u00fcberfahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56412234 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56412234\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f1b033\" data-id=\"9f1b033\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5952b377 elementor-widget elementor-widget-heading\" data-id=\"5952b377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum ist diese F\u00e4hre eine gute Wahl?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-149c538e elementor-widget elementor-widget-text-editor\" data-id=\"149c538e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dunkerque und Calais sind ausgezeichnete H\u00e4fen f\u00fcr die \u00dcberfahrt nach England. Calais bietet die meisten F\u00e4hren pro Tag, w\u00e4hrend Dunkerque weniger \u00fcberf\u00fcllt ist. Viele h\u00e4ufig reisende Personen w\u00e4hlen Dunkerque, weil diese Route in der Regel reibungsloser verl\u00e4uft und weniger Probleme verursacht.<\/p><p>Es ist auch eine kosteng\u00fcnstige \u00dcberfahrt: Der Startpreis liegt zum Zeitpunkt der Erstellung bei 112 \u20ac f\u00fcr 4 Personen in einem Auto. Wenn wir die Berechnung im Buchungsmodul durchf\u00fchren, kommen wir auf einen Preis von 110 \u20ac. Dabei handelt es sich also um ein Einzelticket, aber das f\u00fcr weniger <strong>als 27,50\u202f\u20ac pro Person.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391d662d elementor-widget elementor-widget-image\" data-id=\"391d662d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1286\" height=\"242\" src=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png\" class=\"attachment-full size-full wp-image-140\" alt=\"DFDS Booking\" srcset=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png 1286w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw-300x56.png 300w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw-1024x193.png 1024w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw-768x145.png 768w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw-1200x226.png 1200w\" sizes=\"(max-width: 1286px) 100vw, 1286px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e143da7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e143da7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65760829\" data-id=\"65760829\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-198bb3f1 elementor-widget elementor-widget-heading\" data-id=\"198bb3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die H\u00e4fen f\u00fcr die \u00dcberfahrt von Frankreich nach England<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-487cdbc3 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"487cdbc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d7a5259\" data-id=\"3d7a5259\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30050d34 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"30050d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken.jpg\" class=\"attachment-full size-full wp-image-82\" alt=\"\" srcset=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken.jpg 1600w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken-300x169.jpg 300w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken-1024x576.jpg 1024w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken-768x432.jpg 768w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/Haven-van-Duinkerken-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4295d0c2\" data-id=\"4295d0c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39ea266b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"39ea266b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"LC20lb MBeuO DKV0Md\">D\u00fcnkirchen<\/h3><p>D\u00fcnkirchen ist aus Deutschland gesehen mindestens 2,5 Stunden Reisezeit und eine ideale Alternative zu Calais. Zumindest, wenn man von Frankreich nach England reisen m\u00f6chte. Von D\u00fcnkirchen fahren t\u00e4glich mehrere F\u00e4hren nach Dover. D\u00fcnkirchen liegt direkt an der Grenze zu Belgien. Das DFDS-Terminal befindet sich etwas s\u00fcdlicher, in Richtung Calais. D\u00fcnkirchen selbst ist traditionell eine fl\u00e4mische Stadt und bekannt nicht nur f\u00fcr die \u00dcberfahrt, sondern auch f\u00fcr den Krieg und die Filme \u00fcber D\u00fcnkirchen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37331afe elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37331afe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f3b998f\" data-id=\"5f3b998f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17effcd8 elementor-widget elementor-widget-image\" data-id=\"17effcd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/ferry-terminal-port-of-dover.jpg\" class=\"attachment-full size-full wp-image-81\" alt=\"\" srcset=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/ferry-terminal-port-of-dover.jpg 1200w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/ferry-terminal-port-of-dover-300x200.jpg 300w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/ferry-terminal-port-of-dover-1024x683.jpg 1024w, https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/ferry-terminal-port-of-dover-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8d50175\" data-id=\"8d50175\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-349147d1 elementor-widget elementor-widget-text-editor\" data-id=\"349147d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Dover\u00a0<\/h3><p>Dover liegt auf der anderen Seite des Kanals gegen\u00fcber von D\u00fcnkirchen im Landkreis Kent. In Dover kommen sowohl die F\u00e4hren aus Calais als auch aus D\u00fcnkirchen an. In der Vergangenheit kamen hier auch Boote aus Boulogne und Oostende an, aber diese Verbindungen wurden eingestellt. Deine Alternativen sind jetzt also D\u00fcnkirchen-Dover und Calais-Dover.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26e4be91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26e4be91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-511ef7e6\" data-id=\"511ef7e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7226089 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7226089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die DFDS-Terminals in Calais und D\u00fcnkirchen sind eine halbe Stunde mit dem Auto voneinander entfernt (bei normalem Verkehr). Das ist auch genau der Unterschied in der Dauer der \u00dcberfahrt. Also zeitlich macht es nicht so viel aus, welche \u00dcberfahrt du nimmst.<\/p><p>Es kann nat\u00fcrlich auch sein, dass du den Trubel vermeiden m\u00f6chtest. Oft ist D\u00fcnkirchen dann die bessere Option im Vergleich zum Hafen von Calais.<\/p><p><strong>In Calais hast du \u00fcbrigens auch mehr Auswahl bez\u00fcglich der Anbieter,<\/strong> w\u00e4hrend <strong>von D\u00fcnkirchen nur DFDS f\u00e4hrt.<\/strong><\/p><p>Bei dieser \u00dcberfahrt wird erwartet, dass du mit eigenem Fahrzeug kommst. Es ist nicht m\u00f6glich, nur als Fu\u00dfpassagier zu buchen. In Calais kann man dies zum Beispiel tun, wenn man mit <strong>P&amp;O Ferries<\/strong> bucht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-686dda24 elementor-widget elementor-widget-text-editor\" data-id=\"686dda24\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Buche Economy f\u00fcr einen niedrigeren Preis, Flexi f\u00fcr mehr Flexibilit\u00e4t.<\/p><p>Rechtzeitig f\u00fcr deine \u00dcberfahrt zu buchen hilft oft dabei, ein g\u00fcnstiges Ticket zu finden. Bist du sicher, dass du, wenn du eine \u00dcberfahrt machst, ein Economy-Ticket w\u00e4hlen m\u00f6chtest, das etwas g\u00fcnstiger, aber weniger flexibel ist? M\u00f6chtest du rechtzeitig buchen und sparen, aber etwas mehr Flexibilit\u00e4t, dann w\u00e4hle ein Flexi-Ticket. F\u00fcr einen kleinen Aufpreis hast du dann noch die M\u00f6glichkeit, die Zeit \/ das Datum sp\u00e4ter anzupassen.<\/p><p><a href=\"https:\/\/dover-dunkirk.com\/de\/go\/dunkirk-dover\">Buche diese Route \u2b9e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8137895\" data-id=\"8137895\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bbee700 elementor-widget elementor-widget-shortcode\" data-id=\"6bbee700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe src=\"https:\/\/www.google.com\/maps\/d\/u\/1\/embed?mid=10ciJQAvUxHrw2giKLK79ks6mh0ct5L0&ehbc=2E312F\" width=\"640\" height=\"480\"><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e00d4c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e00d4c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1de80d5c\" data-id=\"1de80d5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e536357 elementor-widget elementor-widget-heading\" data-id=\"7e536357\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"faq\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3bd4179a\" data-id=\"3bd4179a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a2b9bb5 elementor-widget elementor-widget-accordion\" data-id=\"1a2b9bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Muss man f\u00fcr diese \u00dcberfahrt im Voraus buchen?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4391\"><p>Ja, diese \u00dcberfahrt ist sehr stark frequentiert und oft ausgebucht. Es ist daher empfehlenswert, deine Tickets <strong>online im Voraus zu buchen<\/strong>, um sicherzustellen, dass du einen Platz bekommst und eventuell von g\u00fcnstigeren Preisen profitierst.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4392\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-4392\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie gro\u00df ist die Entfernung von D\u00fcnkirchen nach Dover?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4392\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-4392\"><p>Die Entfernung zwischen <strong>D\u00fcnkirchen und Dover<\/strong> betr\u00e4gt ungef\u00e4hr <strong>64 Kilometer<\/strong>. Diese Strecke erm\u00f6glicht eine relativ kurze und komfortable \u00dcberfahrt \u00fcber den \u00c4rmelkanal.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4393\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-4393\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie lange dauert die F\u00e4hre\u00fcberfahrt?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4393\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-4393\"><p>Die \u00dcberfahrt von <strong>D\u00fcnkirchen nach Dover<\/strong> dauert etwa <strong>2 Stunden<\/strong>. Im Vergleich dazu ben\u00f6tigt die \u00dcberfahrt von <strong>Calais nach Dover<\/strong> ungef\u00e4hr <strong>90 Minuten<\/strong>. Die <strong>Eurotunnel-Verbindung<\/strong> ist zwar deutlich schneller (ca. <strong>35 Minuten<\/strong>), jedoch auch deutlich teurer.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4394\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-4394\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Mit wem f\u00e4hrst du auf dieser \u00dcberfahrt?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4394\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-4394\"><p>Auf der Strecke <strong>D\u00fcnkirchen &#8211; Dover<\/strong> ist <strong>DFDS<\/strong> die einzige F\u00e4hrgesellschaft. Du kannst DFDS-Tickets <strong>direkt bei DFDS<\/strong> oder \u00fcber <strong>Directferries.de<\/strong> buchen. Andere Anbieter wie <strong>P&amp;O Ferries<\/strong> und <strong>Stena Line<\/strong> verkehren hingegen von den <strong>Niederlanden<\/strong> und dem nahegelegenen <strong>Calais<\/strong> aus.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Von D\u00fcnkirchen nach Dover In nur 2 Stunden mit der F\u00e4hre bist du in England: Dunkerque-Dover \u21d2 Die beste Alternative f\u00fcr die \u00dcberfahrt von Calais nach Dover \u21d2 Dunkerque ist ein leicht erreichbarer Hafen aus Deutschland. Tickets und Preise D\u00fcnkirchen nach Dover Tickets und Preise Verglichen mit Calais: etwas k\u00fcrzere Anfahrt, etwas l\u00e4ngere \u00dcberfahrt. Buche [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-79","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre<\/title>\n<meta name=\"description\" content=\"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dover-dunkirk.com\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre\" \/>\n<meta property=\"og:description\" content=\"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dover-dunkirk.com\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00fcnkirchen Dover f\u00e4hre\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-09T15:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1286\" \/>\n\t<meta property=\"og:image:height\" content=\"242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\",\"url\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\",\"name\":\"Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/chrome_2YfvNoRTAw.png\",\"datePublished\":\"2025-01-09T12:55:35+00:00\",\"dateModified\":\"2025-01-09T15:44:10+00:00\",\"description\":\"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/chrome_2YfvNoRTAw.png\",\"contentUrl\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/chrome_2YfvNoRTAw.png\",\"width\":1286,\"height\":242,\"caption\":\"DFDS Booking\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"D\u00fcnkirchen nach Dover\",\"item\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von D\u00fcnkirchen nach Dover\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\",\"name\":\"D\u00fcnkirchen Dover f\u00e4hre\",\"description\":\"Von D\u00fcnkirchen nach Dover\",\"publisher\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#organization\",\"name\":\"D\u00fcnkirchen Dover f\u00e4hre\",\"url\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/D.png\",\"contentUrl\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/D.png\",\"width\":512,\"height\":512,\"caption\":\"D\u00fcnkirchen Dover f\u00e4hre\"},\"image\":{\"@id\":\"https:\\\/\\\/dover-dunkirk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre","description":"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dover-dunkirk.com\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre","og_description":"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!","og_url":"https:\/\/dover-dunkirk.com\/de\/","og_site_name":"D\u00fcnkirchen Dover f\u00e4hre","article_modified_time":"2025-01-09T15:44:10+00:00","og_image":[{"width":1286,"height":242,"url":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dover-dunkirk.com\/de\/","url":"https:\/\/dover-dunkirk.com\/de\/","name":"Von D\u00fcnkirchen nach Dover - D\u00fcnkirchen Dover f\u00e4hre","isPartOf":{"@id":"https:\/\/dover-dunkirk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dover-dunkirk.com\/de\/#primaryimage"},"image":{"@id":"https:\/\/dover-dunkirk.com\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png","datePublished":"2025-01-09T12:55:35+00:00","dateModified":"2025-01-09T15:44:10+00:00","description":"Willkommen bei Dover-Dunkerque.com \u2013 Ihre entspannte F\u00e4hr\u00fcberfahrt von D\u00fcnkirchen nach Dover!","breadcrumb":{"@id":"https:\/\/dover-dunkirk.com\/de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dover-dunkirk.com\/de\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dover-dunkirk.com\/de\/#primaryimage","url":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png","contentUrl":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/chrome_2YfvNoRTAw.png","width":1286,"height":242,"caption":"DFDS Booking"},{"@type":"BreadcrumbList","@id":"https:\/\/dover-dunkirk.com\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"D\u00fcnkirchen nach Dover","item":"https:\/\/dover-dunkirk.com\/de\/"},{"@type":"ListItem","position":2,"name":"Von D\u00fcnkirchen nach Dover"}]},{"@type":"WebSite","@id":"https:\/\/dover-dunkirk.com\/de\/#website","url":"https:\/\/dover-dunkirk.com\/de\/","name":"D\u00fcnkirchen Dover f\u00e4hre","description":"Von D\u00fcnkirchen nach Dover","publisher":{"@id":"https:\/\/dover-dunkirk.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dover-dunkirk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dover-dunkirk.com\/de\/#organization","name":"D\u00fcnkirchen Dover f\u00e4hre","url":"https:\/\/dover-dunkirk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dover-dunkirk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/D.png","contentUrl":"https:\/\/dover-dunkirk.com\/de\/wp-content\/uploads\/sites\/2\/2025\/01\/D.png","width":512,"height":512,"caption":"D\u00fcnkirchen Dover f\u00e4hre"},"image":{"@id":"https:\/\/dover-dunkirk.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/pages\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":26,"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/pages\/79\/revisions"}],"predecessor-version":[{"id":149,"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/pages\/79\/revisions\/149"}],"wp:attachment":[{"href":"https:\/\/dover-dunkirk.com\/de\/wp-json\/wp\/v2\/media?parent=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}